{"id":12897,"date":"2024-08-29T14:05:17","date_gmt":"2024-08-29T14:05:17","guid":{"rendered":"https:\/\/manual.classera.com\/?post_type=docs&#038;p=12897"},"modified":"2025-02-21T19:04:21","modified_gmt":"2025-02-21T19:04:21","password":"","slug":"forms-5","status":"publish","type":"docs","link":"https:\/\/manual.classera.com\/ar\/docs\/forms-5\/","title":{"rendered":"\u0627\u0644\u0646\u0645\u0627\u0630\u062c"},"content":{"rendered":"<p>\u062a\u0648\u0641\u0631 \u0644\u0643 \u0634\u0627\u0634\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0648\u0638\u064a\u0641\u0629 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0648\u062a\u0635\u062f\u064a\u0631\u0647\u0627.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"140\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c.png\" alt=\"\" class=\"wp-image-13792\" style=\"width:1024px;height:auto\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c.png 1576w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c-300x70.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c-1024x238.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c-768x178.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c-1536x357.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/\u0646\u0645\u0627\u0630\u062c-18x4.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0645\u0636\u0627\u0641\u0629 \u0628\u0648\u0627\u0633\u0637\u062a\u064a\" \u0644\u062a\u0635\u0641\u064a\u0629 \u0623\u0648 \u0639\u0631\u0636 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u062a\u064a \u0623\u0636\u0641\u062a\u0647\u0627.<\/li>\n\n\n\n<li>\u0631\u0627\u062c\u0639 \u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0645\u0639\u0631\u0648\u0636\u0629 \u0641\u064a \u0627\u0644\u062c\u062f\u0648\u0644\u060c \u0648\u0627\u0644\u062a\u064a \u062a\u062a\u0636\u0645\u0646 \u0623\u0639\u0645\u062f\u0629 \u0644\u0644\u0639\u0646\u0648\u0627\u0646\u060c \u0648\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0625\u063a\u0644\u0627\u0642\u060c \u0648\u0627\u0644\u0625\u062c\u0631\u0627\u0621\u0627\u062a.<\/li>\n\n\n\n<li>\u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0631\u064a\u062f \u062a\u0635\u062f\u064a\u0631 \u0627\u0644\u0642\u0627\u0626\u0645\u0629\u060c \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u062a\u0635\u062f\u064a\u0631 \u0625\u0644\u0649 Excel\" \u0644\u062a\u0646\u0632\u064a\u0644 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0643\u0645\u0644\u0641 Excel.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"214\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25.png\" alt=\"\" class=\"wp-image-13789\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25.png 1569w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25-300x88.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25-1024x299.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25-768x224.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25-1536x448.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-40-25-18x5.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u0646\u0645\u0648\u0630\u062c \u062c\u062f\u064a\u062f\" \u0644\u0625\u0646\u0634\u0627\u0621 \u0646\u0645\u0648\u0630\u062c \u062c\u062f\u064a\u062f.<\/li>\n\n\n\n<li>\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u0646\u0633\u062e \u0627\u0644\u0646\u0645\u0648\u0630\u062c\" \u0644\u0639\u0645\u0644 \u0646\u0633\u062e\u0629 \u0645\u0646 \u0646\u0645\u0648\u0630\u062c \u0645\u0648\u062c\u0648\u062f.<\/li>\n\n\n\n<li>\u0631\u0627\u062c\u0639 \u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0627\u0644\u0645\u0639\u0631\u0648\u0636\u0629 \u0641\u064a \u0627\u0644\u062c\u062f\u0648\u0644\u060c \u0648\u0627\u0644\u062a\u064a \u062a\u062a\u0636\u0645\u0646 \u0623\u0639\u0645\u062f\u0629 \u0644\u0644\u0639\u0646\u0648\u0627\u0646\u060c \u0648\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0628\u062f\u0621\u060c \u0648\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0625\u063a\u0644\u0627\u0642\u060c \u0648\u0627\u0644\u0625\u062c\u0631\u0627\u0621\u0627\u062a.<\/li>\n\n\n\n<li>\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u062a\u0635\u062f\u064a\u0631 \u0625\u0644\u0649 Excel\" \u0644\u062a\u0646\u0632\u064a\u0644 \u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0643\u0645\u0644\u0641 Excel.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"939\" height=\"1024\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11.png\" alt=\"\" class=\"wp-image-13786\" style=\"width:912px;height:auto\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11.png 1587w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11-276x300.png 276w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11-943x1024.png 943w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11-768x834.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11-1414x1536.png 1414w, https:\/\/manual.classera.com\/wp-content\/uploads\/2025\/01\/2025-01-27_4-41-11-11x12.png 11w\" sizes=\"(max-width: 939px) 100vw, 939px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0623\u062f\u062e\u0644 \u0639\u0646\u0648\u0627\u0646 \u0627\u0644\u0646\u0645\u0648\u0630\u062c \u0641\u064a \u0627\u0644\u062d\u0642\u0644 \u0627\u0644\u0645\u062e\u0635\u0635.<\/li>\n\n\n\n<li>\u0627\u0645\u0644\u0623 \u0642\u0633\u0645 \u0627\u0644\u0639\u0646\u0648\u0627\u0646 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0645\u062d\u0631\u0631 \u0627\u0644\u0646\u0635\u0648\u0635.<\/li>\n\n\n\n<li>\u062d\u062f\u062f \u062e\u064a\u0627\u0631 \"\u0639\u0631\u0636 \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\" \u0625\u0630\u0627 \u0644\u0632\u0645 \u0627\u0644\u0623\u0645\u0631.<\/li>\n\n\n\n<li>\u062d\u062f\u062f \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0641\u062a\u062d \u0628\u0627\u0644\u0646\u0642\u0631 \u0639\u0644\u0649 \u0627\u0644\u062d\u0642\u0644 \u0648\u0627\u062e\u062a\u064a\u0627\u0631 \u062a\u0627\u0631\u064a\u062e.<\/li>\n\n\n\n<li>\u062d\u062f\u062f \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0625\u063a\u0644\u0627\u0642 \u0628\u0627\u0644\u0646\u0642\u0631 \u0639\u0644\u0649 \u0627\u0644\u062d\u0642\u0644 \u0648\u0627\u062e\u062a\u064a\u0627\u0631 \u062a\u0627\u0631\u064a\u062e.<\/li>\n\n\n\n<li>\u0642\u0645 \u0628\u062a\u062d\u0645\u064a\u0644 \u0645\u0633\u062a\u0646\u062f \u0627\u0644\u0634\u0631\u0648\u0637 \u0648\u0627\u0644\u0623\u062d\u0643\u0627\u0645 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0632\u0631 \"\u0627\u062e\u062a\u064a\u0627\u0631 \u0645\u0644\u0641\".<\/li>\n\n\n\n<li>\u062d\u062f\u062f \u0627\u0644\u0642\u0633\u0645 \u0645\u0646 \u0627\u0644\u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0645\u0646\u0633\u062f\u0644\u0629.<\/li>\n\n\n\n<li>\u0627\u062e\u062a\u0631 \u062e\u064a\u0627\u0631 \u0627\u0644\u0631\u0624\u064a\u0629: \u0639\u0627\u0645 \u0623\u0648 \u062e\u0627\u0635.<\/li>\n\n\n\n<li>\u0623\u062f\u062e\u0644 \u0623\u064a \u0648\u0635\u0641 \u0625\u0636\u0627\u0641\u064a \u0641\u064a \u0645\u0631\u0628\u0639 \u0627\u0644\u0646\u0635.<\/li>\n\n\n\n<li>\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \"\u062d\u0641\u0638\" \u0644\u062d\u0641\u0638 \u0627\u0644\u0646\u0645\u0648\u0630\u062c.<\/li>\n\n\n\n<li>\u0627\u0633\u062a\u062e\u062f\u0645 \u0632\u0631 \"\u0645\u0639\u0627\u064a\u0646\u0629\" \u0644\u0645\u0631\u0627\u062c\u0639\u0629 \u0627\u0644\u0646\u0645\u0648\u0630\u062c \u0642\u0628\u0644 \u0625\u0646\u0647\u0627\u0626\u0647.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0648\u0641\u0631 \u0644\u0643 \u0634\u0627\u0634\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0648\u0638\u064a\u0641\u0629 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0646\u0645\u0627\u0630\u062c \u0648\u062a\u0635\u062f\u064a\u0631\u0647\u0627.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"doc_category":[362],"doc_tag":[],"class_list":["post-12897","docs","type-docs","status-publish","hentry","doc_category-forms-admission"],"year_month":"2026-05","word_count":229,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"reham mohamed","author_nicename":"r-mohamed","author_url":"https:\/\/manual.classera.com\/ar\/author\/r-mohamed\/"},"doc_category_info":[{"term_name":"Forms","term_url":"https:\/\/manual.classera.com\/ar\/docs-category\/forms-admission\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/12897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/comments?post=12897"}],"version-history":[{"count":1,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/12897\/revisions"}],"predecessor-version":[{"id":16921,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/12897\/revisions\/16921"}],"wp:attachment":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/media?parent=12897"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/doc_category?post=12897"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/doc_tag?post=12897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}