{"id":7181,"date":"2024-04-19T22:30:55","date_gmt":"2024-04-19T22:30:55","guid":{"rendered":"https:\/\/manual.classera.com\/?post_type=docs&#038;p=7181"},"modified":"2025-01-25T05:40:36","modified_gmt":"2025-01-25T05:40:36","password":"","slug":"support-edit","status":"publish","type":"docs","link":"https:\/\/manual.classera.com\/ar\/docs\/support-edit\/","title":{"rendered":"\u0627\u0644\u0627\u0633\u062a\u0628\u064a\u0627\u0646\u0627\u062a | \u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a"},"content":{"rendered":"<figure class=\"wp-block-image alignright size-full\"><img decoding=\"async\" width=\"254\" height=\"136\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0627\u062f\u0648\u0627\u062a-\u0627\u0644\u062a\u0642\u064a\u064a\u0645.png\" alt=\"\" class=\"wp-image-15029\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0627\u062f\u0648\u0627\u062a-\u0627\u0644\u062a\u0642\u064a\u064a\u0645.png 303w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0627\u062f\u0648\u0627\u062a-\u0627\u0644\u062a\u0642\u064a\u064a\u0645-300x155.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0627\u062f\u0648\u0627\u062a-\u0627\u0644\u062a\u0642\u064a\u064a\u0645-18x9.png 18w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/><\/figure>\n\n\n\n<p class=\"translation-block\">\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 <strong>\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u062a\u0642\u064a\u064a\u0645&gt;&gt;\u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a|\u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639\u0627\u062a<\/strong> \u0645\u0646 \u0627\u0644\u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629 \u0644\u0641\u062a\u062d \u0634\u0627\u0634\u0629 <strong>\u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a|\u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639\u0627\u062a<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a<\/h4>\n\n\n\n<p>\u062a\u0639\u0631\u0636 \u0647\u0630\u0647 \u0627\u0644\u0634\u0627\u0634\u0629 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0645\u0639 \u0628\u064a\u0627\u0646\u0627\u062a \u0645\u0631\u0626\u064a\u0629\u060c \u0645\u0645\u0627 \u064a\u062a\u064a\u062d \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0633\u062a\u0637\u0644\u0627\u0639\u060c \u0625\u0631\u0633\u0627\u0644\u0647\u060c \u0648\u0639\u0631\u0636 \u0645\u0642\u0627\u064a\u064a\u0633 \u0645\u0641\u0635\u0644\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0631\u0633\u0648\u0645 \u0627\u0644\u0628\u064a\u0627\u0646\u064a\u0629 \u0627\u0644\u0634\u0631\u064a\u0637\u064a\u0629 \u0644\u0644\u062a\u062d\u0644\u064a\u0644. \u062a\u0633\u0627\u0639\u062f \u0627\u0644\u0634\u0627\u0634\u0629 \u0641\u064a \u0625\u062f\u0627\u0631\u0629 \u0648\u062a\u0642\u064a\u064a\u0645 \u0632\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u0641\u0648\u0641 \u0628\u0634\u0643\u0644 \u0641\u0639\u0627\u0644.<\/p>\n\n\n\n<p><strong>\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0634\u0627\u0634\u0629 \u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a \u0628\u0641\u0639\u0627\u0644\u064a\u0629\u060c \u064a\u0631\u062c\u0649 \u0627\u062a\u0628\u0627\u0639 \u0627\u0644\u062a\u0639\u0644\u064a\u0645\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"398\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a.png\" alt=\"\" class=\"wp-image-15030\" style=\"width:921px;height:auto\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a.png 1587w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a-300x125.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a-1024x426.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a-768x319.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a-1536x639.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/\u0639\u0631\u0628\u064a-18x7.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">\u0641\u064a \u0635\u0641\u062d\u0629 <strong>\u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639\u0627\u062a<\/strong>\u060c \u0623\u062f\u062e\u0644 \u0639\u0646\u0648\u0627\u0646\u064b\u0627 \u0641\u064a \u062d\u0642\u0644 \u0627\u0644\u0628\u062d\u062b \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0631\u063a\u0628 \u0641\u064a \u062a\u0635\u0641\u064a\u0629 \u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639\u0627\u062a\u060c \u062b\u0645 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u0628\u062d\u062b<\/strong> \u0644\u0644\u0639\u062b\u0648\u0631 \u0639\u0644\u0649 \u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639 \u0627\u0644\u0645\u0637\u0644\u0648\u0628.<\/li>\n\n\n\n<li class=\"translation-block\">\u0639\u0631\u0636 \u062a\u0641\u0627\u0635\u064a\u0644 \u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639\u060c \u062d\u062f\u062f \u0627\u0644\u0627\u0633\u062a\u0637\u0644\u0627\u0639 \u0641\u064a \u0627\u0644\u062c\u062f\u0648\u0644\u060c \u062b\u0645 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a<\/strong> \u0641\u064a \u0639\u0645\u0648\u062f <strong>\u0627\u0644\u0625\u062c\u0631\u0627\u0621<\/strong>.<\/li>\n\n\n\n<li>\u0641\u064a \u0627\u0644\u0634\u0627\u0634\u0629 \u0627\u0644\u062a\u0627\u0644\u064a\u0629\u060c \u064a\u0645\u0643\u0646\u0643 \u0639\u0631\u0636 \u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0623\u0641\u0631\u0627\u062f \u0623\u0648 \u0627\u0644\u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u0645\u062a\u0627\u062d\u0629 \u0644\u0644\u062a\u0642\u064a\u064a\u0645. <\/li>\n\n\n\n<li class=\"translation-block\">\u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0631\u064a\u062f \u062a\u0635\u062f\u064a\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0625\u0644\u0649 Excel\u060c \u0641\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u062a\u0635\u062f\u064a\u0631 \u0625\u0644\u0649 Excel<\/strong> \u0623\u0639\u0644\u0649 \u0627\u0644\u0635\u0641\u062d\u0629.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"215\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18.png\" alt=\"\" class=\"wp-image-15031\" style=\"width:1089px;height:auto\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18.png 1581w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18-300x65.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18-1024x223.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18-768x168.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18-1536x335.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-35-18-18x4.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"translation-block\">5. \u0625\u0630\u0627 \u0643\u0646\u062a \u062a\u0631\u064a\u062f \u062a\u0635\u062f\u064a\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0625\u0644\u0649 Excel\u060c \u0641\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u062a\u0635\u062f\u064a\u0631 \u0625\u0644\u0649 Excel<\/strong> \u0623\u0639\u0644\u0649 \u0627\u0644\u0635\u0641\u062d\u0629.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"561\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1.png\" alt=\"\" class=\"wp-image-15032\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1.png 1602w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1-300x100.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1-1024x341.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1-768x256.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1-1536x511.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-36-52-1-18x6.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>6. \u0641\u064a \u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645\u0627\u062a \u0627\u0644\u062a\u0641\u0635\u064a\u0644\u064a\u060c \u064a\u0645\u0643\u0646\u0643 \u0645\u0631\u0627\u062c\u0639\u0629 \u0639\u0646\u0627\u0635\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0648\u0627\u0644\u0645\u0624\u0634\u0631\u0627\u062a \u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0629 \u0644\u0647\u0627. \u064a\u0645\u0643\u0646\u0643 \u0623\u064a\u0636\u064b\u0627 \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0645\u062e\u062a\u0627\u0631 \u0648\u0625\u0636\u0627\u0641\u0629 \u062a\u0639\u0644\u064a\u0642\u0627\u062a \u0625\u0630\u0627 \u0644\u0632\u0645 \u0627\u0644\u0623\u0645\u0631.<\/p>\n\n\n\n<p class=\"translation-block\">7. \u0625\u0630\u0627 \u0643\u0646\u062a \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u062a\u0646\u0632\u064a\u0644 \u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u062a\u0641\u0635\u064a\u0644\u064a\u060c \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631  \u062a\u0635\u062f\u064a\u0631 \u0625\u0644\u0649 Excel \u0641\u064a \u0623\u0639\u0644\u0649 \u0627\u0644\u0635\u0641\u062d\u0629.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u062a\u0642\u064a\u064a\u0645\u0627\u062a\u064a<\/h4>\n\n\n\n<p>\u062a\u0633\u0627\u0639\u062f\u0643 \u0647\u0630\u0647 \u0627\u0644\u0634\u0627\u0634\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u0646\u0642\u0644 \u0648\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0645\u064a\u0632\u0627\u062a\u0647\u0627 \u0644\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0646\u062a\u0627\u0626\u062c \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0648\u0645\u0631\u0627\u062c\u0639\u062a\u0647\u0627. \u062a\u0639\u0631\u0636 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0628\u0634\u0643\u0644 \u0648\u0627\u0636\u062d \u0645\u0639 \u0628\u064a\u0627\u0646\u0627\u062a \u0645\u0631\u0626\u064a\u0629\u060c \u0645\u0645\u0627 \u064a\u062a\u064a\u062d \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0633\u062a\u0637\u0644\u0627\u0639\u060c \u0625\u0631\u0633\u0627\u0644\u0647\u060c \u0648\u0639\u0631\u0636 \u0627\u0644\u0645\u0642\u0627\u064a\u064a\u0633 \u0627\u0644\u062a\u0641\u0635\u064a\u0644\u064a\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0631\u0633\u0648\u0645 \u0627\u0644\u0628\u064a\u0627\u0646\u064a\u0629 \u0627\u0644\u0634\u0631\u064a\u0637\u064a\u0629 \u0644\u062a\u062d\u0644\u064a\u0644 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00.png\" alt=\"\" class=\"wp-image-15034\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00.png 1571w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00-300x167.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00-1024x571.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00-768x428.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00-1536x856.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_11-45-00-18x10.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"translation-block\">\u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0641\u0639\u0651\u0627\u0644 \u0644\u0647\u0630\u0647 \u0627\u0644\u0634\u0627\u0634\u0629\u060c \u064a\u0631\u062c\u0649 \u0627\u062a\u0628\u0627\u0639 \u0627\u0644\u062e\u0637\u0648\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u062a\u0628\u0648\u064a\u0628  <strong>\u062a\u0642\u064a\u064a\u0645\u064a<\/strong> \u0644\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0643.<\/li>\n\n\n\n<li class=\"translation-block\">\u0631\u0627\u062e\u062a\u0631 \u0627\u0633\u062a\u0637\u0644\u0627\u0639\u064b\u0627 \u0645\u0646 \u0627\u0644\u0642\u0627\u0626\u0645\u0629 \u0627\u0644\u0645\u0646\u0633\u062f\u0644\u0629 \u0627\u0644\u0645\u0633\u0645\u0651\u0627\u0629 <strong>\u0627\u062e\u062a\u0631 \u0627\u0633\u062a\u0637\u0644\u0627\u0639<\/strong>.<\/li>\n\n\n\n<li class=\"translation-block\">\u0628\u0639\u062f \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u0627\u0633\u062a\u0628\u064a\u0627\u0646 \u0627\u0644\u0645\u0637\u0644\u0648\u0628\u060c \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u0625\u0631\u0633\u0627\u0644<\/strong> \u0644\u062a\u062d\u0645\u064a\u0644 \u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u062a\u0642\u064a\u064a\u0645.<\/li>\n\n\n\n<li>\u064a\u0631\u062c\u0649 \u0625\u0644\u0642\u0627\u0621 \u0646\u0638\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u0631\u0626\u064a\u0629\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0627\u0644\u0631\u0633\u0648\u0645 \u0627\u0644\u0628\u064a\u0627\u0646\u064a\u0629 \u0627\u0644\u0634\u0631\u064a\u0637\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0648\u0636\u062d \u0645\u0642\u0627\u064a\u064a\u0633 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0645\u062b\u0644 \u0627\u0644\u0645\u062a\u0648\u0633\u0637 \u0627\u0644\u0639\u0627\u0645 \u0648\u0627\u0644\u062f\u0631\u062c\u0627\u062a \u0627\u0644\u0641\u0631\u062f\u064a\u0629.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u0627\u0644\u0632\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u0641\u064a\u0629<\/h4>\n\n\n\n<p>\u0627\u0644\u062e\u0637\u0648\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629 \u0633\u062a\u0633\u0627\u0639\u062f\u0643 \u0639\u0644\u0649 \u0627\u0644\u062a\u0646\u0642\u0644 \u0648\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0634\u0627\u0634\u0629 \u0644\u0625\u062f\u0627\u0631\u0629 \u0648\u062a\u0642\u064a\u064a\u0645 \u0632\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u0641\u0648\u0641 \u0628\u0634\u0643\u0644 \u0641\u0639\u0627\u0644. \u062a\u062a\u064a\u062d \u0647\u0630\u0647 \u0627\u0644\u0634\u0627\u0634\u0629 \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u062a\u0635\u0641\u064a\u0629 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0628\u0646\u0627\u0621\u064b \u0639\u0644\u0649 \u0627\u0644\u062a\u0648\u0627\u0631\u064a\u062e\u060c \u062a\u062e\u0635\u064a\u0635 \u0639\u0631\u0636 \u0627\u0644\u062c\u062f\u0627\u0648\u0644\u060c \u062a\u0635\u062f\u064a\u0631 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a\u060c \u0648\u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u062a\u0642\u0627\u0631\u064a\u0631 \u062a\u0642\u064a\u064a\u0645 \u0645\u0641\u0635\u0644\u0629.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"366\" src=\"http:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17.png\" alt=\"\" class=\"wp-image-15035\" srcset=\"https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17.png 1585w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17-300x122.png 300w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17-1024x417.png 1024w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17-768x313.png 768w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17-1536x626.png 1536w, https:\/\/manual.classera.com\/wp-content\/uploads\/2024\/12\/2024-12-08_10-42-17-18x7.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"translation-block\">\u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0641\u0639\u0651\u0627\u0644 \u0644\u0647\u0630\u0647 \u0627\u0644\u0634\u0627\u0634\u0629\u060c \u064a\u0631\u062c\u0649 \u0627\u062a\u0628\u0627\u0639 \u0627\u0644\u062e\u0637\u0648\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u0628\u0648\u064a\u0628 <strong>\u0632\u064a\u0627\u0631\u0627\u062a \u0635\u0641\u064a\u0629<\/strong> \u0644\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u062a\u0642\u064a\u064a\u0645\u0627\u062a \u0632\u064a\u0627\u0631\u0627\u062a \u0635\u0641\u064a\u0629.<\/li>\n\n\n\n<li class=\"translation-block\">\u0627\u0633\u062a\u062e\u062f\u0645 \u062d\u0642\u0644 <strong>\u0627\u0644\u062a\u0627\u0631\u064a\u062e<\/strong> \u0644\u062a\u0635\u0641\u064a\u0629 \u0627\u0644\u0632\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u0641\u064a\u0629 \u062d\u0633\u0628 \u062a\u0627\u0631\u064a\u062e \u0645\u0639\u064a\u0646\u060c \u062b\u0645 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u0628\u062d\u062b<\/strong> \u0644\u0639\u0631\u0636 \u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629.<\/li>\n\n\n\n<li class=\"translation-block\">\u0642\u0645 \u0628\u062a\u0639\u062f\u064a\u0644 \u0639\u062f\u062f \u0627\u0644\u0635\u0641\u0648\u0641 \u0627\u0644\u0645\u0639\u0631\u0648\u0636\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0632\u0631 <strong>\u0627\u0644\u0635\u0641\u0648\u0641<\/strong>\u060c \u0623\u0648 \u062e\u0635\u0635 \u0627\u0644\u0623\u0639\u0645\u062f\u0629 \u0627\u0644\u0638\u0627\u0647\u0631\u0629 \u0628\u0627\u0644\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u062a\u062e\u0635\u064a\u0635 \u0627\u0644\u0623\u0639\u0645\u062f\u0629<\/strong>.<\/li>\n\n\n\n<li class=\"translation-block\">\u0644\u062a\u0635\u062f\u064a\u0631 \u0628\u064a\u0627\u0646\u0627\u062a \u0627\u0644\u0632\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u0641\u064a\u0629\u060c \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u062a\u0635\u062f\u064a\u0631<\/strong>.<\/li>\n\n\n\n<li class=\"translation-block\">\u0627\u0628\u062d\u062b \u0639\u0646 \u0632\u064a\u0627\u0631\u0629 \u0627\u0644\u0641\u0635\u0644 \u0627\u0644\u0645\u0637\u0644\u0648\u0628\u0629 \u0641\u064a \u0627\u0644\u062c\u062f\u0648\u0644\u060c \u062b\u0645 \u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 <strong>\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u062a\u0642\u0631\u064a\u0631<\/strong> \u0641\u064a \u0639\u0645\u0648\u062f <strong>\u0627\u0644\u0625\u062c\u0631\u0627\u0621<\/strong> \u0644\u0639\u0631\u0636 \u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u062a\u0641\u0635\u064a\u0644\u064a \u0623\u0648 \u062a\u0642\u064a\u064a\u0645\u0647.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Click Evaluation Tools&gt;&gt;Evaluations| Surveys from the main menu to open the Evaluations| Surveys screen. Evaluations This screen displays evaluation reports with visualized data, allowing users to select a survey, submit it, and view detailed metrics through bar charts for analysis. It helps you to manage and evaluate class visits efficiently. To use the Evaluations screen [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"doc_category":[91],"doc_tag":[],"class_list":["post-7181","docs","type-docs","status-publish","hentry","doc_category-evaluation-tools-teacher"],"year_month":"2026-05","word_count":473,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"reham mohamed","author_nicename":"r-mohamed","author_url":"https:\/\/manual.classera.com\/ar\/author\/r-mohamed\/"},"doc_category_info":[{"term_name":"Evaluation Tools","term_url":"https:\/\/manual.classera.com\/ar\/docs-category\/evaluation-tools-teacher\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/7181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/comments?post=7181"}],"version-history":[{"count":1,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/7181\/revisions"}],"predecessor-version":[{"id":15850,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/docs\/7181\/revisions\/15850"}],"wp:attachment":[{"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/media?parent=7181"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/doc_category?post=7181"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/manual.classera.com\/ar\/wp-json\/wp\/v2\/doc_tag?post=7181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}